{"id":10791,"date":"2025-09-08T14:28:18","date_gmt":"2025-09-08T12:28:18","guid":{"rendered":"https:\/\/vaeter-und-karriere.de\/blog\/?p=10791"},"modified":"2025-09-28T14:49:34","modified_gmt":"2025-09-28T12:49:34","slug":"es-geht-weiter","status":"publish","type":"post","link":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/2025\/09\/08\/es-geht-weiter\/","title":{"rendered":"&#8230; es geht weiter"},"content":{"rendered":"<p><img loading=\"lazy\" class=\" wp-image-10785 alignleft\" src=\"https:\/\/vaeter-und-karriere.de\/blog\/wp-content\/uploads\/2024\/07\/HGMarko.png\" alt=\"\" width=\"290\" height=\"307\" srcset=\"https:\/\/vaeter-und-karriere.de\/blog\/wp-content\/uploads\/2024\/07\/HGMarko.png 664w, https:\/\/vaeter-und-karriere.de\/blog\/wp-content\/uploads\/2024\/07\/HGMarko-283x300.png 283w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/>15 Monate herrschte auf diesem Kanal Funkstille, ich habe nach dem Ende meiner T\u00e4tigkeit als Fachreferent in der Gesch\u00e4ftsstelle der LAG V\u00e4terarbeit lange nachgedacht, welchen Beitrag ich noch leisten kann und will und an welcher Stelle ich meine Expertise und Kompetenzen einsetzen kn ann.<\/p>\n<p>Dies werde ich an folgenden drei Stellen tun:<\/p>\n<p>Im V\u00e4terexpertennetz Deutschland VEND-eV werden wir beginnend mit einer Fachveranstaltung am 21. November das 20 j\u00e4hrige Bestehen des VEND zum Anlass nehmen, zur\u00fcckzublicken und Weichenstellungen f\u00fcr eine zukunftsf\u00e4hige, vielf\u00e4ltige und wirksame V\u00e4terarbeit formulieren, die wir dann gemeinsam auf Bundesebene angehen werden.<\/p>\n<p>Mit der Fachstelle V\u00e4terarbeit werde ich an die vom Land bis 2019 gef\u00f6rderte Arbeit in NRW ankn\u00fcpfen und Organisationen in NRW bei der Weiterentwicklung ihrer Angebote f\u00fcr V\u00e4ter begleiten.<\/p>\n<p>Im VaeterBlog werde ich \u00fcber diese Arbeit sowie die Entwicklung der V\u00e4ter-, Familien- und Gleichstellungspolitik, wie seit 2006 gewohnt, kommentierend berichten.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>15 Monate herrschte auf diesem Kanal Funkstille, ich habe nach dem Ende meiner T\u00e4tigkeit als Fachreferent in der Gesch\u00e4ftsstelle der LAG V\u00e4terarbeit lange nachgedacht, welchen Beitrag ich noch leisten kann und will und an welcher Stelle ich meine Expertise und Kompetenzen einsetzen kn ann. Dies werde ich an folgenden drei Stellen tun: Im V\u00e4terexpertennetz Deutschland [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[56,22],"tags":[],"_links":{"self":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10791"}],"collection":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10791"}],"version-history":[{"count":1,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10791\/revisions"}],"predecessor-version":[{"id":10792,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10791\/revisions\/10792"}],"wp:attachment":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}