{"id":10114,"date":"2021-03-03T11:11:06","date_gmt":"2021-03-03T11:11:06","guid":{"rendered":"http:\/\/vaeter-und-karriere.de\/blog\/?p=10114"},"modified":"2021-03-03T11:11:08","modified_gmt":"2021-03-03T11:11:08","slug":"vaeter-sind-ein-schluessel-damit-vereinbarkeitsmodelle-gelingen","status":"publish","type":"post","link":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/2021\/03\/03\/vaeter-sind-ein-schluessel-damit-vereinbarkeitsmodelle-gelingen\/","title":{"rendered":"\u201aV\u00e4ter sind ein Schl\u00fcssel, damit Vereinbarkeitsmodelle gelingen\u2018"},"content":{"rendered":"\n<p>\u201eEs bedarf einer mutigen Reform\u201c \u2013 Interview mit PD Dr.\nMartin Bujard (Pr\u00e4sident der Evangelischen Arbeitsgemeinschaft Familie, eaf)\n\u00fcber die Rolle der V\u00e4ter in Vereinbarkeitsmodellen von Familie und Beruf <\/p>\n\n\n\n<p>Herr Bujard, die eaf b\u00fcndelt die vielen evangelischen\nInstitutionen im Bereich Familie und gibt ihnen eine Stimme gegen\u00fcber der\nPolitik. Dabei geht es um Kinderrechte und Kinderschutz, um Unterst\u00fctzung f\u00fcr\nFamilien und um Elternschaft mit all ihren Anforderungen und Bed\u00fcrfnissen. Was\nmacht die Tagung \u201eM\u00e4nner Leben Beruf\u201c f\u00fcr Sie als Pr\u00e4sident der eaf interessant\nund wo sehen Sie die Ber\u00fchrungspunkte? <\/p>\n\n\n\n<p>Martin Bujard: Die Debatten um die Vereinbarkeit von Familie\nund Beruf werden vielfach auf Frauen, auf M\u00fctter reduziert. Dabei sind V\u00e4ter\nein Schl\u00fcssel, damit Vereinbarkeitsmodelle gelingen. Das ist lange untersch\u00e4tzt\nworden, auch die Politik hinkt hier teilweise hinterher. Wir d\u00fcrfen M\u00e4nner nicht\nals \u201eBystanders\u201c in diesem Diskurs betrachten, der sie eigentlich nichts\nangeht, sondern m\u00fcssen sie mit hineinholen. Das genau macht die Tagung, indem\nsie V\u00e4ter in den Mittelpunkt stellt. Das ist gut! Denn wir brauchen bei diesem\nThema mehr kulturelle Akzeptanz, vor allem auch bei den Arbeitgebern. <\/p>\n\n\n\n<p>Im Einladungstext wird nicht nur auf V\u00e4ter, sondern\ngenereller auf die \u201eBed\u00fcrfnisse eines ver\u00e4nderten M\u00e4nnerlebens\u201c Bezug genommen.\nWie nehmen Sie diese wahr? <\/p>\n\n\n\n<p>\u201eDas M\u00e4nnerleben\u201c gibt es nat\u00fcrlich nicht, aber es gibt\nschon gewisse Generationenerfahrungen, die sich in der Tat ver\u00e4ndern. Die\nmittlere M\u00e4nnergeneration hat jetzt 13 Jahre Elterngeld erlebt \u2013 diese\nM\u00f6glichkeiten hatten ihre V\u00e4ter \u2013 die Gro\u00dfv\u00e4tergeneration \u2013 nicht. Leider nutzt\nnur ein gutes Drittel der V\u00e4ter Elternzeit. Diejenigen aber haben in der\nElternzeit erfahren, dass es begl\u00fcckend ist, sich in die Familie einzubringen,\ndie F\u00fcrsorge f\u00fcr die Kinder mit zu \u00fcbernehmen. V\u00e4ter arbeiten zum Teil mehr als\nM\u00e4nner ohne Kinder im Beruf, mit Familienarbeit kommen viele auf bis zu 60-70\nStunden pro Woche, um aktive V\u00e4ter zu sein. Wie M\u00fctter sind sie in der Rushhour\ndes Lebens, wenn die Kinder klein sind. H\u00e4ufig k\u00f6nnen V\u00e4ter ihren Wunsch, ein\naktiver Vater zu sein, aber nicht so umsetzen, wie sie m\u00f6chten. Die noch\nj\u00fcngere M\u00e4nnergeneration ist mit einem egalit\u00e4ren Weltbild gro\u00df geworden: Sie\nm\u00f6chten die Dinge gern partnerschaftlich regeln und f\u00fcr beide ein erf\u00fcllendes\nBerufs- und Privatleben realisieren. Aber sobald Kinder da sind, stellen sie\nfest, dass Wunsch und Wirklichkeit nicht leicht in Einklang zu bringen sind. <\/p>\n\n\n\n<p>Kommt hier Ihr Konzept der \u201edynamischen Familienarbeitszeit\u201c\nins Spiel, mit dem Sie im Tagungsprogramm angek\u00fcndigt sind? <\/p>\n\n\n\n<p>Ja, das Konzept sieht vor, eben diese Kluft zwischen Wunsch\nund Wirklichkeit zu reduzieren. Vereinbarkeit findet im Lebenslauf statt. Wenn\ndie Kinder sehr klein sind, ist der Bedarf an Zeit f\u00fcr F\u00fcrsorge sehr gro\u00df.\nHeute sieht das dann meist so aus, dass M\u00fctter halbtags Erwerbsarbeit nachgehen\nund V\u00e4ter voll und mehr arbeiten. Deshalb schlagen wir mit der dynamischen\nFamilienarbeitszeit einen Korridor vor, der etwa bis zum Schuleintritt der\nKinder greifen soll und in dem beide Elternteile 60-90 Prozent, also in\nvollzeitnaher Teilzeit arbeiten. Ganz wichtig w\u00e4re, dass dabei die\nunterliegenden Vorstellungen von Karriere bei den Arbeitgebern sich \u00e4ndern. In\nder Rushhour des Lebens muss es f\u00fcr M\u00e4nner und Frauen m\u00f6glich gemacht werden,\nbei tempor\u00e4r reduzierter Arbeitszeit keine Karriereeinbu\u00dfen zu erleiden und\npartnerschaftlich Familie zu leben. Wir lesen seit Jahren die immer gleichen\nErgebnisse in Umfragen, dass M\u00e4nner mehr Zeit f\u00fcr die Familie m\u00f6chten und viele\nFrauen gern st\u00e4rker am Berufsleben teilhaben w\u00fcrden. Das m\u00fcssen wir nun endlich\nin die Realit\u00e4t umsetzen, da bedarf es einer mutigen Reform. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.presseportal.de\/pm\/147043\/4851400\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Quelle (\u00f6ffnet in neuem Tab)\">Quelle<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eEs bedarf einer mutigen Reform\u201c \u2013 Interview mit PD Dr. Martin Bujard (Pr\u00e4sident der Evangelischen Arbeitsgemeinschaft Familie, eaf) \u00fcber die Rolle der V\u00e4ter in Vereinbarkeitsmodellen von Familie und Beruf Herr Bujard, die eaf b\u00fcndelt die vielen evangelischen Institutionen im Bereich Familie und gibt ihnen eine Stimme gegen\u00fcber der Politik. Dabei geht es um Kinderrechte und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[43,31],"tags":[91],"_links":{"self":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10114"}],"collection":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10114"}],"version-history":[{"count":1,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10114\/revisions"}],"predecessor-version":[{"id":10115,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10114\/revisions\/10115"}],"wp:attachment":[{"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vaeter-und-karriere.de\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}